{"id":3377,"date":"2026-02-10T20:20:15","date_gmt":"2026-02-10T19:20:15","guid":{"rendered":"https:\/\/elbohiorevista.com\/?p=3377"},"modified":"2026-02-10T20:25:32","modified_gmt":"2026-02-10T19:25:32","slug":"contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos","status":"publish","type":"post","link":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/","title":{"rendered":"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_3377\" class=\"pvc_stats all  \" data-element-id=\"3377\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/elbohiorevista.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<h2 class=\"wp-block-heading\">El \u00faltimo informe realizado por la Red Costera Bonaerense advirti\u00f3 sobre el preocupante aumento de residuos de ese material, que ahora representa la mayor proporci\u00f3n. Alertan sobre su impacto en la fauna marina<\/h2>\n\n\n\n<p>Por<a href=\"https:\/\/www.infobae.com\/autor\/myrna-leal\/\">Myrna Leal<\/a><a href=\"https:\/\/profile.google.com\/cp\/CgsvbS8wMTI1aDVmaA\" rel=\"noreferrer noopener\" target=\"_blank\">Seguir en<\/a><\/p>\n\n\n\n<p>12 Ene, 2026 10:48 a.m. EST<\/p>\n\n\n\n<p>Guardar<img loading=\"lazy\" decoding=\"async\" alt=\"El relevamiento 2026 mostr\u00f3 que\" height=\"506\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/R46OKPWDRREHVL7R44LMBZ2QZY.jpg?auth=524c744507408b53bae326147c6042ca21db9ed8900f043927b724e0c5e9f144&amp;smart=true&amp;width=350&amp;height=158&amp;quality=85\" width=\"1120\">El relevamiento 2026 mostr\u00f3 que el 78% de los residuos en playas bonaerenses son pl\u00e1sticos (Mundo Marino)<\/p>\n\n\n\n<p>El \u00faltimo relevamiento sobre&nbsp;<strong>basura costera en playas bonaerenses<\/strong>&nbsp;confirm\u00f3 que la&nbsp;<strong>presencia de&nbsp;<\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/01\/12\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\" target=\"_blank\"><strong>pl\u00e1sticos&nbsp;<\/strong><\/a><strong>contin\u00faa dominando de manera abrumadora los residuos marinos<\/strong>, con impactos directos sobre los ecosistemas y la&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.infobae.com\/tag\/fauna-marina\/\" target=\"_blank\">fauna local.<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/09\/como-satelites-y-tecnicas-ultrasensibles-permiten-detectar-microplasticos-y-nanoplasticos-en-mares-sedimentos-y-tejidos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a class=\"recommended-card recommended-card--infobae recommended-card--first\" href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/09\/como-satelites-y-tecnicas-ultrasensibles-permiten-detectar-microplasticos-y-nanoplasticos-en-mares-sedimentos-y-tejidos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/MDNONGJJXKA6DZ5QUAEBHM7HAY.jpg?auth=c3924c5cb2ebad9eab57221dba12ee1f023d383087c9c2fa0c458c1223ad4f2c&amp;smart=true&amp;width=256&amp;height=140&amp;quality=85\" alt=\"C\u00f3mo sat\u00e9lites y t\u00e9cnicas ultrasensibles permiten detectar micropl\u00e1sticos y nanopl\u00e1sticos en mares, sedimentos y tejidos\"\/><\/a><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/09\/como-satelites-y-tecnicas-ultrasensibles-permiten-detectar-microplasticos-y-nanoplasticos-en-mares-sedimentos-y-tejidos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Te puede interesar:<strong>C\u00f3mo sat\u00e9lites y t\u00e9cnicas ultrasensibles permiten detectar micropl\u00e1sticos y nanopl\u00e1sticos en mares, sedimentos y tejidos<\/strong><\/a><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/09\/como-satelites-y-tecnicas-ultrasensibles-permiten-detectar-microplasticos-y-nanoplasticos-en-mares-sedimentos-y-tejidos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>El estudio, impulsado por la&nbsp;<strong>Red Costera Bonaerense (RECOBO)<\/strong>&nbsp;que integran medio centenar de instituciones no gubernamentales y gubernamentales de 17 municipios, arroj\u00f3 que un total de<strong>&nbsp;78,36% de los desechos registrados correspondieron a distintos tipos de pl\u00e1sticos<\/strong>. Este porcentaje representa un nuevo m\u00e1ximo frente a los a\u00f1os previos y evidencia la magnitud de la problem\u00e1tica, pese a los esfuerzos de prevenci\u00f3n y concientizaci\u00f3n.<\/p>\n\n\n\n<p>Seg\u00fan el relevamiento difundido en enero de&nbsp;<strong>2025<\/strong>&nbsp;los pl\u00e1sticos hab\u00edan representado el&nbsp;<strong>74,05%<\/strong>&nbsp;del total de residuos.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/08\/como-la-adaptacion-de-los-bosques-al-cambio-climatico-podria-definir-el-riesgo-de-incendios-forestales\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a class=\"recommended-card recommended-card--infobae recommended-card--first\" href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/08\/como-la-adaptacion-de-los-bosques-al-cambio-climatico-podria-definir-el-riesgo-de-incendios-forestales\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/F3WI35CQZVAQ7G7LUNDA4DEFOM.jpg?auth=d4ce801da23af5388bbbe7c7b51234bc40a57cd27a71d716b0a9a87e5382e88f&amp;smart=true&amp;width=256&amp;height=140&amp;quality=85\" alt=\"C\u00f3mo la adaptaci\u00f3n de los bosques al cambio clim\u00e1tico podr\u00eda definir el riesgo de incendios forestales\"\/><\/a><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/08\/como-la-adaptacion-de-los-bosques-al-cambio-climatico-podria-definir-el-riesgo-de-incendios-forestales\/\" target=\"_blank\" rel=\"noreferrer noopener\">Te puede interesar:<strong>C\u00f3mo la adaptaci\u00f3n de los bosques al cambio clim\u00e1tico podr\u00eda definir el riesgo de incendios forestales<\/strong><\/a><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/08\/como-la-adaptacion-de-los-bosques-al-cambio-climatico-podria-definir-el-riesgo-de-incendios-forestales\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>En el informe de 2026, con datos relevados el a\u00f1o pasado, los autores detallaron que&nbsp;<strong>39.826 residuos<\/strong>&nbsp;fueron contabilizados en 17 puntos del litoral bonaerense, con la colaboraci\u00f3n de&nbsp;<strong>457 voluntarios y 50 instituciones<\/strong>. La superficie analizada fue de&nbsp;<strong>172.359 metros cuadrados<\/strong>&nbsp;de playas.<img loading=\"lazy\" decoding=\"async\" alt=\"La contaminaci\u00f3n pl\u00e1stica en el\" height=\"1524\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/AEFXRXISRNEVHFFEHACHH5PWMU.jpg?auth=2b20ceb837001741a14d09e0fd72fb55cba885858aef33a2512923b074264666&amp;smart=true&amp;width=350&amp;height=494&amp;quality=85\" width=\"1080\">La contaminaci\u00f3n pl\u00e1stica en el litoral bonaerense alcanz\u00f3 un m\u00e1ximo hist\u00f3rico este a\u00f1o (Gr\u00e1fico Infobae)<\/p>\n\n\n\n<p>Dentro de la categor\u00eda de&nbsp;<strong>pl\u00e1sticos,&nbsp;<\/strong>los&nbsp;<strong>fragmentos&nbsp;<\/strong>constituyeron el \u00edtem m\u00e1s frecuente, con un&nbsp;<strong>27,32%<\/strong>&nbsp;respecto del total de residuos pl\u00e1sticos registrados. Estos fragmentos provienen de la degradaci\u00f3n de objetos de mayor tama\u00f1o y, al no biodegradarse, se fragmentan en piezas cada vez m\u00e1s peque\u00f1as, incluyendo micropl\u00e1sticos que pueden incorporarse a la cadena alimentaria.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/10\/las-huellas-humanas-en-el-clima-desde-el-calentamiento-de-la-atmosfera-al-impacto-en-las-profundidades-del-oceano\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a class=\"recommended-card recommended-card--infobae recommended-card--first\" href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/10\/las-huellas-humanas-en-el-clima-desde-el-calentamiento-de-la-atmosfera-al-impacto-en-las-profundidades-del-oceano\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/DYNTVHUXABEOVIV4QTPYGR4DTI.jpg?auth=2166640b9c2b06cf7147d412a1fc7f1e938cc117a85b73de172c58b17afc59ee&amp;smart=true&amp;width=258&amp;height=140&amp;quality=85\" alt=\"Las huellas humanas en el clima: desde el calentamiento de la atm\u00f3sfera al impacto en las profundidades del oc\u00e9ano\"\/><\/a><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/10\/las-huellas-humanas-en-el-clima-desde-el-calentamiento-de-la-atmosfera-al-impacto-en-las-profundidades-del-oceano\/\" target=\"_blank\" rel=\"noreferrer noopener\">Te puede interesar:<strong>Las huellas humanas en el clima: desde el calentamiento de la atm\u00f3sfera al impacto en las profundidades del oc\u00e9ano<\/strong><\/a><a href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/02\/10\/las-huellas-humanas-en-el-clima-desde-el-calentamiento-de-la-atmosfera-al-impacto-en-las-profundidades-del-oceano\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>Datos del informe subrayan la gravedad del cuadro a nivel mundial, al citar estad\u00edsticas de la Organizaci\u00f3n de las Naciones Unidas:&nbsp;<strong>la producci\u00f3n global de pl\u00e1sticos ya supera los 430 millones de toneladas anuales<\/strong>, y constituye entre el 80 y 90% de los residuos marinos del planeta.<\/p>\n\n\n\n<p>En el relevamiento bonaerense,&nbsp;<strong>las colillas de cigarrillo se ubicaron en segundo lugar<\/strong>, con&nbsp;<strong>el 21,34% de los desechos detectados<\/strong>. Aunque de menor tama\u00f1o, estas contienen acetato de celulosa, un&nbsp;<strong>pl\u00e1stico no biodegradable,&nbsp;<\/strong>y liberan compuestos t\u00f3xicos como nicotina y metales pesados. Este tipo de residuos representa una amenaza grave para la fauna, ya que aves y otros animales marinos pueden ingerirlas accidentalmente, y las sustancias desprendidas afectan tanto la calidad del agua como la salud de las especies costeras.<img loading=\"lazy\" decoding=\"async\" alt=\"Fragmentos pl\u00e1sticos, colillas y envoltorios\" height=\"3456\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/KWCKMQZZPRGJPLZV52BJ6WIK2E.jpg?auth=adba2c9bfdaeeb08ede121f62ce917b813b77dbe2e7e07461a6a143f2190414c&amp;smart=true&amp;width=350&amp;height=263&amp;quality=85\" width=\"4608\">Fragmentos pl\u00e1sticos, colillas y envoltorios dominan la basura costera en Buenos Aires<\/p>\n\n\n\n<p>Entre los residuos adicionales encontrados figuran restos de&nbsp;<strong>redes, sogas, l\u00edneas de pesca y descartes asociados a la actividad pesquera<\/strong>, particularmente peligrosos para la fauna marina por los riesgos de enredos, lesiones y restricciones para la alimentaci\u00f3n y el desplazamiento.&nbsp;<strong>Mam\u00edferos marinos, aves y tortugas<\/strong>&nbsp;son v\u00edctimas habituales de estos materiales, que a menudo permanecen en el ambiente una vez que dejan de tener uso productivo.<\/p>\n\n\n\n<p>La bi\u00f3loga&nbsp;<strong>Karina \u00c1lvarez<\/strong>, responsable de proyectos de conservaci\u00f3n en la Fundaci\u00f3n Mundo Marino, explic\u00f3 a&nbsp;<em>Infobae<\/em>&nbsp;la composici\u00f3n de los residuos pl\u00e1sticos totales recopilados: \u201c<strong>De los 39.826 residuos, 31.209 fueron distintos tipos de pl\u00e1sticos<\/strong>. Dentro de los pl\u00e1sticos, los fragmentos representan el 27,32%, las colillas de cigarrillo el 21,43%, los envoltorios pl\u00e1sticos el 8,9%, las bolsas pl\u00e1sticas el 8,17% y el telgopor el 7,6%\u201d. Subray\u00f3 que cada una de estas fracciones exige&nbsp;<strong>estrategias espec\u00edficas&nbsp;<\/strong>de educaci\u00f3n ambiental y campa\u00f1as de reducci\u00f3n dirigida.<img loading=\"lazy\" decoding=\"async\" alt=\"El pl\u00e1stico de un solo\" height=\"937\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/3NLCVZMPBVGKXMAAPXAL5YMTCI.png?auth=73e43ed97d02bac749d8cc972db882960d095cbbc9f36015bfdd62bbf343c75e&amp;smart=true&amp;width=350&amp;height=627&amp;quality=85\" width=\"523\">El pl\u00e1stico de un solo uso compone entre 60 y 95% de la contaminaci\u00f3n oce\u00e1nica<\/p>\n\n\n\n<p>El relevamiento de RECOBO coincidi\u00f3, en sus conclusiones, con el&nbsp;<strong>balance anual de asistencia a fauna marina de la Fundaci\u00f3n Mundo Marino<\/strong>&nbsp;en 2025, que cit\u00f3 la desnutrici\u00f3n y la presi\u00f3n humana \u2014principalmente vinculada a la<strong>&nbsp;ingesti\u00f3n o enredo con pl\u00e1sticos<\/strong>\u2014 como causas preponderantes de ingreso de animales al centro de rescate.<\/p>\n\n\n\n<p>La contaminaci\u00f3n impacta especialmente sobre tortugas marinas y aves. Seg\u00fan el informe,<strong>&nbsp;las tortugas suelen confundir pl\u00e1sticos, bolsas y envoltorios con alimento natural,<\/strong>&nbsp;lo que potencia el riesgo de obstrucci\u00f3n intestinal, desnutrici\u00f3n y cuadros cl\u00ednicos complejos. Adem\u00e1s, en aves marinas y costeras se registran casos de debilidad o par\u00e1lisis ocasionados por intoxicaciones derivadas de la basura, incluidas enfermedades bacterianas como el botulismo aviar, cuyas toxinas proliferan en ambientes alterados y cargados de residuos urbanos.<img loading=\"lazy\" decoding=\"async\" alt=\"Los micropl\u00e1sticos y macropl\u00e1sticos ponen\" height=\"4608\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/TUANEBCC4NDQXD4P745GX4Z5WQ.jpg?auth=7fb58647c02386961f894e79ad64ce736297abc8374ef6f726af86066f061916&amp;smart=true&amp;width=350&amp;height=467&amp;quality=85\" width=\"3456\">Los micropl\u00e1sticos y macropl\u00e1sticos ponen en riesgo a tortugas, aves y mam\u00edferos marinos<\/p>\n\n\n\n<p>El&nbsp;<strong>Censo Provincial de Basura Costera Marina<\/strong>, iniciado en 2016, funciona como herramienta de seguimiento sistem\u00e1tico. Desde 2025, las organizaciones aliadas utilizan el nombre de&nbsp;<strong>RECOBO<\/strong>&nbsp;para sus iniciativas. Las campa\u00f1as comprenden, adem\u00e1s, tareas de articulaci\u00f3n con municipios y el fortalecimiento de pol\u00edticas p\u00fablicas sobre residuos.<\/p>\n\n\n\n<p>Entre las localidades censadas figuran&nbsp;<strong>San Pedro, Punta Lara, Punta Indio, Reserva Natural El Destino, San Clemente del Tuy\u00fa, Santa Teresita, Mar de Aj\u00f3, Pinamar, Villa Gesell, Mar del Plata, Necochea, Quequ\u00e9n, Bah\u00eda Blanca y otras<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 indic\u00f3 el informe anterior sobre basura costera<\/h2>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"La persistencia de pl\u00e1sticos causa\" height=\"3712\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/76ZPMDZCPVEF7FRJHJKIVGFEUM.jpg?auth=74147c98c4ec6eaa9915663b4985d9a9db035a88d9338dafe6f8e1222086ad02&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"5568\">La persistencia de pl\u00e1sticos causa enredos, lesiones y desnutrici\u00f3n en la fauna marina<\/p>\n\n\n\n<p>En la comparaci\u00f3n con el&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.infobae.com\/america\/medio-ambiente\/2025\/01\/28\/plasticos-y-colillas-de-cigarrillo-dominan-las-playas-bonaerenses-segun-el-censo-de-basura-costera-marina\/\" target=\"_blank\">relevamiento difundido en&nbsp;<strong>enero de 2025<\/strong><\/a>&nbsp;\u2014<strong>el 74,05%<\/strong>&nbsp;en dicho a\u00f1o\u2014, con un total de&nbsp;<strong>49.913 residuos<\/strong>&nbsp;identificados en 19 localidades y una superficie barrida de&nbsp;<strong>297.636 metros cuadrados<\/strong>. Los resultados se\u00f1alaron que, al igual que en 2026, la eliminaci\u00f3n de residuos pl\u00e1sticos es un reto persistente y dif\u00edcil de revertir. En ese censo, los materiales de un solo uso acapararon el 14,17% del total, seguidos por fragmentos pl\u00e1sticos, colillas de cigarrillo y bolsas.<\/p>\n\n\n\n<p>\u00c1lvarez indic\u00f3 que la presencia de pl\u00e1sticos afecta a la fauna costera de modo alarmante. \u201cEl 96% de las&nbsp;<strong>tortugas verdes marinas vivas<\/strong>&nbsp;que ingresan a nuestro centro de rescate presentan distintos tipos de residuos pl\u00e1sticos en su sistema digestivo\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, especies emblem\u00e1ticas como el&nbsp;<strong>delf\u00edn franciscana<\/strong>&nbsp;constituyen indicadores cr\u00edticos. Seg\u00fan dijo&nbsp;<strong>Pablo Denuncio<\/strong>, investigador del CONICET, en una nota anterior para&nbsp;<em>Infobae<\/em>, \u201cel porcentaje de Franciscanas afectadas por macropl\u00e1sticos en su sistema digestivo sigue en un 20 a 25%. Si se lo analiza desde la perspectiva de los micropl\u00e1sticos, en un estudio de noviembre de 2024, ese porcentaje alcanz\u00f3 el 100%\u201d.<img loading=\"lazy\" decoding=\"async\" alt=\"Los fragmentos pl\u00e1sticos se consolidan\" height=\"866\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/UJTE5TTIRBE2ZNH7WSMFV6RBAA.jpg?auth=106256a30a3c564670c00d2ddad2c069a73df02e97155a375fbce8ee6cbc126c&amp;smart=true&amp;width=350&amp;height=213&amp;quality=85\" width=\"1420\">Los fragmentos pl\u00e1sticos se consolidan como el residuo m\u00e1s com\u00fan en la costa<\/p>\n\n\n\n<p>El material de apoyo t\u00e9cnico elaborado por&nbsp;<strong>Guadalupe M. \u00c1lvarez<\/strong>&nbsp;para RECOBO, detall\u00f3 que los pl\u00e1sticos de un solo uso componen entre&nbsp;<strong>60 y 95% de la contaminaci\u00f3n pl\u00e1stica en los oc\u00e9anos<\/strong>, y advirti\u00f3 que la masa total de pl\u00e1sticos producidos en la historia duplica actualmente la biomasa de todos los animales terrestres y marinos.<\/p>\n\n\n\n<p>Los informes internacionales citados remarcan, adem\u00e1s, que los&nbsp;<strong>micropl\u00e1sticos y nanopl\u00e1sticos<\/strong>&nbsp;han ingresado a la cadena tr\u00f3fica, alcanzando adem\u00e1s a los&nbsp;<strong>seres humanos:<\/strong>&nbsp;se calcula que cada persona ingiere el equivalente a&nbsp;<strong>una tarjeta de cr\u00e9dito por semana, es decir unos 5 gramos<\/strong>.<\/p>\n\n\n\n<p>El pl\u00e1stico, fabricado a partir de&nbsp;<strong>combustibles f\u00f3siles,&nbsp;<\/strong>suma a los riesgos su persistencia y los compuestos qu\u00edmicos utilizados en su fabricaci\u00f3n, muchos de ellos&nbsp;<strong>t\u00f3xicos y prohibidos,<\/strong>&nbsp;aunque solo para algunos usos. La exposici\u00f3n humana a sustancias como el&nbsp;<strong>Bisfenol A<\/strong>&nbsp;(BPA) se verifica a trav\u00e9s de alimentos, agua y aire, con efectos potenciales para el metabolismo, la funci\u00f3n hormonal y la salud en general.<img loading=\"lazy\" decoding=\"async\" alt=\"Las redes pesqueras abandonadas amenazan\" height=\"3024\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/L4TWJFBFDBBOXH6ZJQ6662Q44Q.jpg?auth=9c83f2a29d33b4335e34809d4f8a7678ad8e3774189f58a28d85b2c9c4f91621&amp;smart=true&amp;width=350&amp;height=263&amp;quality=85\" width=\"4032\">Las redes pesqueras abandonadas amenazan la supervivencia de especies marinas<\/p>\n\n\n\n<p>A escala ambiental, los pl\u00e1sticos originan m\u00faltiples efectos:&nbsp;<strong>desde la pseudo saciedad y asfixia en especies marinas<\/strong>, bloqueos alimentarios,&nbsp;<strong>lesiones internas y enredos fatales,<\/strong>&nbsp;hasta la propagaci\u00f3n de especies invasoras, alteraci\u00f3n del sustrato marino, y afectaciones econ\u00f3micas debidas a la p\u00e9rdida de valor paisaj\u00edstico y da\u00f1os a actividades como la pesca. El fen\u00f3meno conocido como&nbsp;<strong>\u201cpesca fantasma\u201d<\/strong>&nbsp;describe la problem\u00e1tica de&nbsp;<strong>redes abandonadas&nbsp;<\/strong>que contin\u00faan matando animales sin control ni utilidad.<\/p>\n\n\n\n<p>La comparaci\u00f3n entre los resultados de 2026 y 2025 revela que la contaminaci\u00f3n por pl\u00e1sticos mantiene su liderazgo como amenaza en las costas bonaerenses. Los datos recabados por&nbsp;<strong>RECOBO<\/strong>&nbsp;refuerzan el llamado urgente a reducir el uso de pl\u00e1sticos, mejorar la gesti\u00f3n de residuos y fortalecer las acciones de prevenci\u00f3n, en un escenario donde tanto la fauna como la salud humana permanecen en riesgo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fuente: https:\/\/www.infobae.com\/america\/medio-ambiente\/2026\/01\/12\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_3377\" class=\"pvc_stats all  \" data-element-id=\"3377\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/elbohiorevista.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>El \u00faltimo informe realizado por la Red Costera Bonaerense advirti\u00f3 sobre el preocupante aumento de residuos de ese material, que ahora representa la mayor proporci\u00f3n. Alertan sobre su impacto en la fauna marina PorMyrna LealSeguir en 12 Ene, 2026 10:48 a.m. EST GuardarEl relevamiento 2026 mostr\u00f3 que el 78% de los residuos en playas bonaerenses&#8230;<\/p>\n","protected":false},"author":3,"featured_media":3378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,16],"tags":[],"class_list":["post-3377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contaminacion","category-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos - Revista Electr\u00f3nica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos - Revista Electr\u00f3nica\" \/>\n<meta property=\"og:description\" content=\"El \u00faltimo informe realizado por la Red Costera Bonaerense advirti\u00f3 sobre el preocupante aumento de residuos de ese material, que ahora representa la mayor proporci\u00f3n. Alertan sobre su impacto en la fauna marina PorMyrna LealSeguir en 12 Ene, 2026 10:48 a.m. EST GuardarEl relevamiento 2026 mostr\u00f3 que el 78% de los residuos en playas bonaerenses...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Electr\u00f3nica\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T19:20:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T19:25:32+00:00\" \/>\n<meta name=\"author\" content=\"Gustavo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\"},\"author\":{\"name\":\"Gustavo\",\"@id\":\"https:\/\/elbohiorevista.com\/#\/schema\/person\/0e8cf5fa11f825488d369dcce056a2a6\"},\"headline\":\"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos\",\"datePublished\":\"2026-02-10T19:20:15+00:00\",\"dateModified\":\"2026-02-10T19:25:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\"},\"wordCount\":1606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/elbohiorevista.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif\",\"articleSection\":[\"Contaminaci\u00f3n\",\"Medio Ambiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\",\"url\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\",\"name\":\"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos - Revista Electr\u00f3nica\",\"isPartOf\":{\"@id\":\"https:\/\/elbohiorevista.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif\",\"datePublished\":\"2026-02-10T19:20:15+00:00\",\"dateModified\":\"2026-02-10T19:25:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage\",\"url\":\"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif\",\"contentUrl\":\"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif\",\"width\":992,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elbohiorevista.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elbohiorevista.com\/#website\",\"url\":\"https:\/\/elbohiorevista.com\/\",\"name\":\"Revista Electr\u00f3nica\",\"description\":\"! Por un medio ambiente en equilibrio !\",\"publisher\":{\"@id\":\"https:\/\/elbohiorevista.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elbohiorevista.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elbohiorevista.com\/#organization\",\"name\":\"Revista Electr\u00f3nica\",\"url\":\"https:\/\/elbohiorevista.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elbohiorevista.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2025\/01\/cropped-cropped-logo-revista.png\",\"contentUrl\":\"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2025\/01\/cropped-cropped-logo-revista.png\",\"width\":250,\"height\":72,\"caption\":\"Revista Electr\u00f3nica\"},\"image\":{\"@id\":\"https:\/\/elbohiorevista.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/elbohiorevista.com\/#\/schema\/person\/0e8cf5fa11f825488d369dcce056a2a6\",\"name\":\"Gustavo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elbohiorevista.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/06c17b8f7748d78ad0fcb3705bd671b35984711fc2d8ad2a15995c5b3b88ed95?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/06c17b8f7748d78ad0fcb3705bd671b35984711fc2d8ad2a15995c5b3b88ed95?s=96&d=mm&r=g\",\"caption\":\"Gustavo\"},\"sameAs\":[\"http:\/\/elbohiorevista.com\"],\"url\":\"https:\/\/elbohiorevista.com\/index.php\/author\/garen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos - Revista Electr\u00f3nica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/","og_locale":"es_ES","og_type":"article","og_title":"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos - Revista Electr\u00f3nica","og_description":"El \u00faltimo informe realizado por la Red Costera Bonaerense advirti\u00f3 sobre el preocupante aumento de residuos de ese material, que ahora representa la mayor proporci\u00f3n. Alertan sobre su impacto en la fauna marina PorMyrna LealSeguir en 12 Ene, 2026 10:48 a.m. EST GuardarEl relevamiento 2026 mostr\u00f3 que el 78% de los residuos en playas bonaerenses...","og_url":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/","og_site_name":"Revista Electr\u00f3nica","article_published_time":"2026-02-10T19:20:15+00:00","article_modified_time":"2026-02-10T19:25:32+00:00","author":"Gustavo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#article","isPartOf":{"@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/"},"author":{"name":"Gustavo","@id":"https:\/\/elbohiorevista.com\/#\/schema\/person\/0e8cf5fa11f825488d369dcce056a2a6"},"headline":"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos","datePublished":"2026-02-10T19:20:15+00:00","dateModified":"2026-02-10T19:25:32+00:00","mainEntityOfPage":{"@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/"},"wordCount":1606,"commentCount":0,"publisher":{"@id":"https:\/\/elbohiorevista.com\/#organization"},"image":{"@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage"},"thumbnailUrl":"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif","articleSection":["Contaminaci\u00f3n","Medio Ambiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/","url":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/","name":"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos - Revista Electr\u00f3nica","isPartOf":{"@id":"https:\/\/elbohiorevista.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage"},"image":{"@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage"},"thumbnailUrl":"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif","datePublished":"2026-02-10T19:20:15+00:00","dateModified":"2026-02-10T19:25:32+00:00","breadcrumb":{"@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#primaryimage","url":"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif","contentUrl":"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2026\/02\/playa-y-plastico.avif","width":992,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/elbohiorevista.com\/index.php\/2026\/02\/10\/contaminacion-en-las-costas-bonaerenses-el-78-de-la-basura-en-las-playas-son-plasticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elbohiorevista.com\/"},{"@type":"ListItem","position":2,"name":"Contaminaci\u00f3n en las costas bonaerenses: el 78% de la basura en las playas son pl\u00e1sticos"}]},{"@type":"WebSite","@id":"https:\/\/elbohiorevista.com\/#website","url":"https:\/\/elbohiorevista.com\/","name":"Revista Electr\u00f3nica","description":"! Por un medio ambiente en equilibrio !","publisher":{"@id":"https:\/\/elbohiorevista.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elbohiorevista.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elbohiorevista.com\/#organization","name":"Revista Electr\u00f3nica","url":"https:\/\/elbohiorevista.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elbohiorevista.com\/#\/schema\/logo\/image\/","url":"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2025\/01\/cropped-cropped-logo-revista.png","contentUrl":"https:\/\/elbohiorevista.com\/wp-content\/uploads\/2025\/01\/cropped-cropped-logo-revista.png","width":250,"height":72,"caption":"Revista Electr\u00f3nica"},"image":{"@id":"https:\/\/elbohiorevista.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elbohiorevista.com\/#\/schema\/person\/0e8cf5fa11f825488d369dcce056a2a6","name":"Gustavo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elbohiorevista.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/06c17b8f7748d78ad0fcb3705bd671b35984711fc2d8ad2a15995c5b3b88ed95?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06c17b8f7748d78ad0fcb3705bd671b35984711fc2d8ad2a15995c5b3b88ed95?s=96&d=mm&r=g","caption":"Gustavo"},"sameAs":["http:\/\/elbohiorevista.com"],"url":"https:\/\/elbohiorevista.com\/index.php\/author\/garen\/"}]}},"_links":{"self":[{"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/posts\/3377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/comments?post=3377"}],"version-history":[{"count":2,"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/posts\/3377\/revisions"}],"predecessor-version":[{"id":3381,"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/posts\/3377\/revisions\/3381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/media?parent=3377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/categories?post=3377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elbohiorevista.com\/index.php\/wp-json\/wp\/v2\/tags?post=3377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}